{"id":42387,"date":"2025-05-13T12:13:03","date_gmt":"2025-05-13T10:13:03","guid":{"rendered":"https:\/\/rentaltec.com\/product\/tds3054-4-ch-500-mhz-digital-oscilloscope\/"},"modified":"2026-06-26T13:45:23","modified_gmt":"2026-06-26T11:45:23","slug":"tds3054-4-ch-500-mhz-digital-oscilloscope","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/de\/produkt\/tds3054-4-ch-500-mhz-digital-oscilloscope\/","title":{"rendered":"TDS3054 4 Ch 500 MHz Digital Oscilloscope"},"content":{"rendered":"<p>Das TDS3054 geh\u00f6rt zur Oszilloskopfamilie TDS3000 \u2013 der preisg\u00fcnstigsten und portabelsten digitalen Phosphoroszilloskop-Familie (DPO) auf dem Markt. DPOs verf\u00fcgen \u00fcber ein farblich abgestuftes Display, das Informationen zur H\u00e4ufigkeit von Signalamplituden und -breiten liefert. Dies erleichtert dem Anwender das Auffinden und Charakterisieren von Signalverl\u00e4ufen, die mit herk\u00f6mmlichen digitalen Speicheroszilloskopen oft schwer zu erkennen sind. Die hohe Aktualisierungsrate von DPOs erm\u00f6glicht zudem die einfache Erfassung und Darstellung seltener Signalverl\u00e4ufe oder -variationen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das TDS3054 geh\u00f6rt zur Oszilloskopfamilie TDS3000 \u2013 der preisg\u00fcnstigsten und portabelsten digitalen Phosphoroszilloskop-Familie (DPO) auf dem Markt. DPOs verf\u00fcgen \u00fcber ein farblich abgestuftes Display, das Informationen zur H\u00e4ufigkeit von Signalamplituden und -breiten liefert. Dies erleichtert dem Anwender das Auffinden und Charakterisieren von Signalverl\u00e4ufen, die mit herk\u00f6mmlichen digitalen Speicheroszilloskopen oft schwer zu erkennen sind. Die hohe [&hellip;]<\/p>\n","protected":false},"featured_media":51324,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1640],"product_cat":[1740,1749,1739],"product_tag":[],"class_list":{"0":"post-42387","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-tektronix-de","7":"product_cat-allgemeine-pruf-und-messtechnik","8":"product_cat-oszilloskope-und-tastkopfe--2ghz","9":"product_cat-pruf-und-messtechnik","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product\/42387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media\/51324"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media?parent=42387"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/manufacturer?post=42387"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_cat?post=42387"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_tag?post=42387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}