{"id":42837,"date":"2025-05-13T12:01:01","date_gmt":"2025-05-13T10:01:01","guid":{"rendered":"https:\/\/rentaltec.com\/product\/bsx320-bit-error-rate-tester-pat-gen-error-analyzr-up-to-32-gb-s\/"},"modified":"2026-06-26T13:42:17","modified_gmt":"2026-06-26T11:42:17","slug":"bsx320-bit-error-rate-tester-pat-gen-error-analyzr-up-to-32-gb-s","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/de\/produkt\/bsx320-bit-error-rate-tester-pat-gen-error-analyzr-up-to-32-gb-s\/","title":{"rendered":"BSX320 Bit Error Rate Tester Pat Gen &#038; Error Analyzr up to 32 Gb\/s"},"content":{"rendered":"<p>Der Bitfehlerratentester Tektronix BSX320 BERTScope der BSX-Serie ist eine Empf\u00e4ngertestplattform, die die neuen Gen4-Standards und dar\u00fcber hinaus unterst\u00fctzt. Dank leistungsstarker Datenverarbeitung und interner Sendeentzerrung erm\u00f6glicht der BSX320 BERTScope protokollbasiertes Handshake-Verfahren und die Synchronisierung mit dem Pr\u00fcfling (DUT), einschlie\u00dflich interaktivem Link-Training mit Datenraten von bis zu 32 Gbit\/s. Als Teil der BSX-Serie verk\u00fcrzt der BSX320 die Zeit f\u00fcr die Fehlersuche in der physikalischen Schicht und beim Link-Training und bietet den schnellsten Weg zur Konformit\u00e4t mit einer Vielzahl von Standards. Hauptmerkmale und Spezifikationen des Tektronix BSX320: Mustergenerierung und Fehleranalyse bis zu 32 Gbit\/s; Optionale integrierte 4-Tap-Sendeentzerrung mit Unterst\u00fctzung f\u00fcr interaktives Link-Training; Protokollorientierte und bitorientierte Multi-Chain-Mustersequenzierung mit erweitertem Muster-\/Sequenzeditor; Benutzerdefinierte Detektormusteranpassung mit Stimulus-Response-Feedback; Patentierte Fehlerortanalyse \u2013 geht \u00fcber die BER-Messung hinaus und bietet Einblicke in die Fehlerquellen durch die Analyse von Korrelationen und deterministischen Fehlermustern; Optionale Vorw\u00e4rtsfehlerkorrekturanalyse erm\u00f6glicht die Simulation der Fehlerrate nach der FEC basierend auf gemessenen Fehlerortmustern; Integrierte Augendiagrammanalyse mit BER-Korrelation einschlie\u00dflich Maskentest, Jitter-Peak, BER-Kontur; Optionale Jitter-Map; Umfassende Jitter-Zerlegung \u2013 mit langen Mustern (z. B. PRBS-31). Der Tektronix BSX320 Bitfehlerratentester kann bei Rentaltec gemietet werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Bitfehlerratentester Tektronix BSX320 BERTScope der BSX-Serie ist eine Empf\u00e4ngertestplattform, die die neuen Gen4-Standards und dar\u00fcber hinaus unterst\u00fctzt. Dank leistungsstarker Datenverarbeitung und interner Sendeentzerrung erm\u00f6glicht der BSX320 BERTScope protokollbasiertes Handshake-Verfahren und die Synchronisierung mit dem Pr\u00fcfling (DUT), einschlie\u00dflich interaktivem Link-Training mit Datenraten von bis zu 32 Gbit\/s. Als Teil der BSX-Serie verk\u00fcrzt der BSX320 die [&hellip;]<\/p>\n","protected":false},"featured_media":51113,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1640],"product_cat":[1740,1741,1739],"product_tag":[],"class_list":{"0":"post-42837","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-tektronix-de","7":"product_cat-allgemeine-pruf-und-messtechnik","8":"product_cat-bitfehlerraten-tester-ber-bert","9":"product_cat-pruf-und-messtechnik","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product\/42837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media\/51113"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media?parent=42837"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/manufacturer?post=42837"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_cat?post=42837"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_tag?post=42837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}