{"id":43569,"date":"2025-05-13T11:37:57","date_gmt":"2025-05-13T09:37:57","guid":{"rendered":"https:\/\/rentaltec.com\/product\/n9952a-fieldfox-handheld-microwave-analyser-50-ghz-24-mm-m\/"},"modified":"2026-06-26T13:35:25","modified_gmt":"2026-06-26T11:35:25","slug":"n9952a-fieldfox-handheld-microwave-analyser-50-ghz-24-mm-m","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/de\/produkt\/n9952a-fieldfox-handheld-microwave-analyser-50-ghz-24-mm-m\/","title":{"rendered":"N9952A FieldFox handheld microwave analyser, 50 GHz, 2,4 mm (m)"},"content":{"rendered":"<p>Der Keysight N9952A ist ein FieldFox-Handmikrowellenanalysator f\u00fcr den Frequenzbereich von 300 kHz bis 50 GHz. Er ist robust genug f\u00fcr h\u00e4rteste Arbeitsumgebungen und erf\u00fcllt die Anforderungen der US-Milit\u00e4rstandards (MIL). Der Analysator l\u00e4sst sich mit optionalem Vektornetzwerkanalysator (VNA), Spektrumanalysator, integriertem Leistungsmesser, Vektorvoltmeter und weiteren Komponenten erweitern. Er vereint die Funktionen eines Kabel- und Antennenanalysators, Spektrumanalysators und Vektornetzwerkanalysators. Er dient zur Analyse von S-Parametern, Fehlerortung, Kabeltrimmung, R\u00fcckflussd\u00e4mpfung, Einf\u00fcgungsd\u00e4mpfung\/-verst\u00e4rkung, Interferenzanalyse und Leistungsmessung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Keysight N9952A ist ein FieldFox-Handmikrowellenanalysator f\u00fcr den Frequenzbereich von 300 kHz bis 50 GHz. Er ist robust genug f\u00fcr h\u00e4rteste Arbeitsumgebungen und erf\u00fcllt die Anforderungen der US-Milit\u00e4rstandards (MIL). Der Analysator l\u00e4sst sich mit optionalem Vektornetzwerkanalysator (VNA), Spektrumanalysator, integriertem Leistungsmesser, Vektorvoltmeter und weiteren Komponenten erweitern. Er vereint die Funktionen eines Kabel- und Antennenanalysators, Spektrumanalysators und [&hellip;]<\/p>\n","protected":false},"featured_media":50671,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1614],"product_cat":[1755,1739,1765],"product_tag":[],"class_list":{"0":"post-43569","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-de","7":"product_cat-funk-und-mikrowelle","8":"product_cat-pruf-und-messtechnik","9":"product_cat-spektrum-und-signalanalysatoren-265-ghz","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product\/43569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media\/50671"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media?parent=43569"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/manufacturer?post=43569"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_cat?post=43569"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_tag?post=43569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}