{"id":44841,"date":"2025-05-13T11:57:07","date_gmt":"2025-05-13T09:57:07","guid":{"rendered":"https:\/\/rentaltec.com\/product\/zva24-24ghz-vector-network-analyzer-3-5-mm-m\/"},"modified":"2026-06-26T13:41:02","modified_gmt":"2026-06-26T11:41:02","slug":"zva24-24ghz-vector-network-analyzer-3-5-mm-m","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/de\/produkt\/zva24-24ghz-vector-network-analyzer-3-5-mm-m\/","title":{"rendered":"ZVA24 24GHz Vector Network Analyzer, 3.5 mm (m)"},"content":{"rendered":"<p>Das Rohde &#038; Schwarz ZVA24 erm\u00f6glicht pr\u00e4zise Filtermessungen mit maximalem Dynamikbereich sowie lineare und nichtlineare Messungen an Verst\u00e4rkern, Mischern, Empf\u00e4ngern und Transceivern. Dank seiner schnellen Synthesizer, der gro\u00dfen ZF-Bandbreite und des hohen Dynamikbereichs bietet das Rohde &#038; Schwarz ZVA24 au\u00dfergew\u00f6hnlich kurze Messzeiten in Labor und Produktion. Es unterst\u00fctzt zudem die simultane Messung von Rauschzahl und S-Parametern. Frequenzbereich: 10 MHz bis 24 GHz. Impulsprofilmessungen mit 12,5 ns Aufl\u00f6sung. Echte Differenzmessungen zur zuverl\u00e4ssigen Charakterisierung aktiver Bauelemente mit symmetrischen Anschl\u00fcssen. Gro\u00dfer Dynamikbereich (typisch): > 140 dB. Hohe Ausgangsleistung (typisch): > 15 dBm. Gro\u00dfe ZF-Bandbreite: 1\/5\/30 MHz. Hohe Messgeschwindigkeit: < 3,5 \u00b5s pro Messpunkt. Vielseitige Kalibrierverfahren: TOSM, TRL\/LRL, TOM, TRM, TNA, UOSM. Automatische Kalibriereinheiten.\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Rohde &#038; Schwarz ZVA24 erm\u00f6glicht pr\u00e4zise Filtermessungen mit maximalem Dynamikbereich sowie lineare und nichtlineare Messungen an Verst\u00e4rkern, Mischern, Empf\u00e4ngern und Transceivern. Dank seiner schnellen Synthesizer, der gro\u00dfen ZF-Bandbreite und des hohen Dynamikbereichs bietet das Rohde &#038; Schwarz ZVA24 au\u00dfergew\u00f6hnlich kurze Messzeiten in Labor und Produktion. Es unterst\u00fctzt zudem die simultane Messung von Rauschzahl und [&hellip;]<\/p>\n","protected":false},"featured_media":51034,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1631],"product_cat":[1755,1758,1739],"product_tag":[],"class_list":{"0":"post-44841","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-rohde-schwarz-de","7":"product_cat-funk-und-mikrowelle","8":"product_cat-netzwerkanalysatoren-und-kalibriersatze--20-ghz","9":"product_cat-pruf-und-messtechnik","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product\/44841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media\/51034"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media?parent=44841"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/manufacturer?post=44841"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_cat?post=44841"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_tag?post=44841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}