{"id":44901,"date":"2025-05-13T11:56:05","date_gmt":"2025-05-13T09:56:05","guid":{"rendered":"https:\/\/rentaltec.com\/product\/smw200a-b1056-100-khz-56-ghz-single-channel-vector-signal-generator-1-85-mm-f\/"},"modified":"2026-08-25T15:39:21","modified_gmt":"2026-08-25T13:39:21","slug":"smw200a-b1056-100-khz-56-ghz-single-channel-vector-signal-generator-1-85-mm-f","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/de\/produkt\/smw200a-b1056-100-khz-56-ghz-single-channel-vector-signal-generator-1-85-mm-f\/","title":{"rendered":"SMW200A-B1056 100 kHz &#8211; 56 GHz Single Channel Vector Signal Generator, 1.85 mm (f)"},"content":{"rendered":"<p>Der R&amp;S\u00aeSMW200A ist der Vektorsignalgenerator f\u00fcr anspruchsvollste Anwendungen. Dank seiner Flexibilit\u00e4t, Leistungsf\u00e4higkeit und intuitiven Bedienung eignet er sich ideal zur Erzeugung komplexer, digital modulierter Signale in hoher Qualit\u00e4t. \u2022 Frequenzbereich: 56 GHz \u2022 Modulationsbandbreite: 2 GHz \u2022 Integriertes Fading mit bis zu 800 MHz Bandbreite und bis zu 8&#215;8 MIMO \u2022 Signalgenerierung f\u00fcr alle g\u00e4ngigen digitalen Kommunikationsstandards \u2022 Fortschrittlicher GNSS- und Radarsimulator<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der R&amp;S\u00aeSMW200A ist der Vektorsignalgenerator f\u00fcr anspruchsvollste Anwendungen. Dank seiner Flexibilit\u00e4t, Leistungsf\u00e4higkeit und intuitiven Bedienung eignet er sich ideal zur Erzeugung komplexer, digital modulierter Signale in hoher Qualit\u00e4t. \u2022 Frequenzbereich: 56 GHz \u2022 Modulationsbandbreite: 2 GHz \u2022 Integriertes Fading mit bis zu 800 MHz Bandbreite und bis zu 8&#215;8 MIMO \u2022 Signalgenerierung f\u00fcr alle g\u00e4ngigen [&hellip;]<\/p>\n","protected":false},"featured_media":76614,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1631],"product_cat":[1755,1739,1763],"product_tag":[],"class_list":["post-44901","product","type-product","status-publish","has-post-thumbnail","manufacturer-rohde-schwarz-de","product_cat-funk-und-mikrowelle","product_cat-pruf-und-messtechnik","product_cat-signalgeneratoren-8-ghz","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product\/44901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media\/76614"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media?parent=44901"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/manufacturer?post=44901"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_cat?post=44901"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_tag?post=44901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}