{"id":44985,"date":"2025-05-13T11:55:07","date_gmt":"2025-05-13T09:55:07","guid":{"rendered":"https:\/\/rentaltec.com\/product\/smr40-1-ghz-to-40-ghz-cw-generator-2-92-mm-f\/"},"modified":"2026-06-26T13:40:30","modified_gmt":"2026-06-26T11:40:30","slug":"smr40-1-ghz-to-40-ghz-cw-generator-2-92-mm-f","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/de\/produkt\/smr40-1-ghz-to-40-ghz-cw-generator-2-92-mm-f\/","title":{"rendered":"SMR40 1Ghz &#8211; 40GHz CW generator, 2,92 mm (f)"},"content":{"rendered":"<p>Hervorragendes Preis-Leistungs-Verh\u00e4ltnis. Die vielf\u00e4ltigen Optionen er\u00f6ffnen ein breites Anwendungsfeld in Produktion und Forschung &#038; Entwicklung, wo der R&#038;S SMR als Synthesizer oder vollst\u00e4ndiger Signalgenerator eingesetzt werden kann.<\/p>\n<p>Ausgestattet mit dem optionalen analogen Frequenz- und Pegel-Sweep ist der R&#038;S SMR ein idealer Tracking-Generator f\u00fcr die Skalarnetzwerkanalyse, und der interne ZF-Aufw\u00e4rtswandler erm\u00f6glicht die Erzeugung vektormodulierter Signale bis zu 40 GHz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hervorragendes Preis-Leistungs-Verh\u00e4ltnis. Die vielf\u00e4ltigen Optionen er\u00f6ffnen ein breites Anwendungsfeld in Produktion und Forschung &#038; Entwicklung, wo der R&#038;S SMR als Synthesizer oder vollst\u00e4ndiger Signalgenerator eingesetzt werden kann. Ausgestattet mit dem optionalen analogen Frequenz- und Pegel-Sweep ist der R&#038;S SMR ein idealer Tracking-Generator f\u00fcr die Skalarnetzwerkanalyse, und der interne ZF-Aufw\u00e4rtswandler erm\u00f6glicht die Erzeugung vektormodulierter Signale bis [&hellip;]<\/p>\n","protected":false},"featured_media":53543,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1631],"product_cat":[1755,1739,1763],"product_tag":[],"class_list":{"0":"post-44985","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-rohde-schwarz-de","7":"product_cat-funk-und-mikrowelle","8":"product_cat-pruf-und-messtechnik","9":"product_cat-signalgeneratoren-8-ghz","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product\/44985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media\/53543"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media?parent=44985"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/manufacturer?post=44985"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_cat?post=44985"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_tag?post=44985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}