{"id":45579,"date":"2025-05-14T12:23:59","date_gmt":"2025-05-14T10:23:59","guid":{"rendered":"https:\/\/rentaltec.com\/product\/n4691b-m0f-2-port-300-khz-26-5-ghz-ecal-module-3-5-mm-m-f\/"},"modified":"2026-06-26T13:32:10","modified_gmt":"2026-06-26T11:32:10","slug":"n4691b-m0f-2-port-300-khz-26-5-ghz-ecal-module-3-5-mm-m-f","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/de\/produkt\/n4691b-m0f-2-port-300-khz-26-5-ghz-ecal-module-3-5-mm-m-f\/","title":{"rendered":"N4691B-M0F 2-port, 300 kHz &#8211; 26.5 GHz Ecal module, 3.5 mm (m-f)"},"content":{"rendered":"<p>Das Keysight N4691B-M0F 2-Port-Mikrowellen-Elektronikkalibrierungsmodul (ECal) (3,5-mm-Klinkenstecker) deckt einen Frequenzbereich von 300 kHz bis 26,5 GHz ab und ist mit den Netzwerkanalysatoren FieldFox, PNA-L und PNA kompatibel. Es wird direkt von den Netzwerkanalysatoren der PNA-Serie gesteuert und ben\u00f6tigt keinen externen PC. Schlie\u00dfen Sie das Keysight N4691B-M0F einfach \u00fcber die USB-Schnittstelle des Netzwerkanalysators an und steuern Sie die Kalibrierung \u00fcber die Tasten an der Vorderseite der PNA-Serie oder automatisch \u00fcber das Benutzerprogramm. Die spezifischen S-Parameter-Daten des Keysight N4691B werden im Speicher des Moduls gespeichert und w\u00e4hrend der Kalibrierung zur Berechnung der Fehlerterme des Netzwerkanalysators verwendet. Das Schnittstellenmodul dient als Verbindung zwischen dem Parallelport des VNA, dem Parallelport des Keysight N4691B-M0F und dem externen Netzteil.<\/p>\n<p>Merkmale und Spezifikationen:<\/p>\n<p>* Ideale Kalibriertechnik f\u00fcr die Fertigung<\/p>\n<p>* Ersetzt herk\u00f6mmliche Kalibrierverfahren mit mechanischen Standards<\/p>\n<p>* Reduziert Bedienungsfehler und erm\u00f6glicht pr\u00e4zise Kalibrierungen<\/p>\n<p>* Verringert den Verschlei\u00df der Steckverbinder und senkt so die Reparaturkosten sowohl der Testanschluss-Steckverbinder als auch der Kalibrierstandards<\/p>\n<p>* Schnellere Kalibrierung mit nur einer Verbindung<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agilent (Keysight) N4691B-M0F 2-port, 300 kHz &#8211; 26.5 GHz Ecal module with 3.5 mm connectors (m-f). Includes wrenches and USB cable.<\/p>\n","protected":false},"featured_media":50481,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1614],"product_cat":[1755,1758,1739],"product_tag":[],"class_list":{"0":"post-45579","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-de","7":"product_cat-funk-und-mikrowelle","8":"product_cat-netzwerkanalysatoren-und-kalibriersatze--20-ghz","9":"product_cat-pruf-und-messtechnik","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product\/45579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media\/50481"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media?parent=45579"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/manufacturer?post=45579"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_cat?post=45579"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_tag?post=45579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}