{"id":47409,"date":"2025-05-14T12:01:16","date_gmt":"2025-05-14T10:01:16","guid":{"rendered":"https:\/\/rentaltec.com\/product\/81130a-400-660-mhz-pulse-data-generator\/"},"modified":"2026-08-25T12:12:23","modified_gmt":"2026-08-25T10:12:23","slug":"81130a-400-660-mhz-pulse-data-generator","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/de\/produkt\/81130a-400-660-mhz-pulse-data-generator\/","title":{"rendered":"81130A 400\/660 MHz Pulse Data Generator"},"content":{"rendered":"<p>Der Keysight 81130A ist mit einem oder zwei Keysight 81131A Ausgangsmodulen ein pr\u00e4ziser 400-MHz-Impulsdatengenerator f\u00fcr Ein- und Zweikanalbetrieb. Mit einem oder zwei Keysight 81132A Ausgangsmodulen wird der Keysight 81130A sogar zu einem pr\u00e4zisen 600-MHz-\/1,32-Gbit\/s-Impulsdatengenerator f\u00fcr Ein- und Zweikanalbetrieb. Dank seines PLL-Oszillators bietet der 81130A eine h\u00f6here Genauigkeit bei Verz\u00f6gerung und Impulsbreite als der 81110A. Dieser Pr\u00e4zisionsoszillator ist jedoch nicht triggerbar. Im Vergleich zum 81110A verf\u00fcgt der 81130A \u00fcber einen gr\u00f6\u00dferen, segmentierbaren Speicher (64 kbit). Seine Funktionen f\u00fcr Z\u00e4hlschleifen und sequenzielle PRBS bieten volle Flexibilit\u00e4t f\u00fcr serielle Datenanforderungen wie Datenkommunikationsnachrichten und Initialisierungsroutinen. Zwei Kan\u00e4le k\u00f6nnen intern per EXOR-Verkn\u00fcpfung (Exponentialfunktion) addiert werden. Die vier unabh\u00e4ngigen Zeitflanken erm\u00f6glichen die Erzeugung von Impulsen mit nahezu beliebiger Form in einem einzigen Signal. Je nach Ausgangsmodultyp sind die Impuls\u00fcberg\u00e4nge w\u00e4hlbar (800 ps oder 1,6 ns, 81131A) oder auf 500 ps (81132A) festgelegt. Die Quellimpedanz betr\u00e4gt 50 Ohm, die Ausgangsspannung an 50 Ohm bis zu 3,8 Vpp (81131A) bzw. 2,5 Vpp (81132A). Hinweis: Jeder Keysight 81130A 400-MHz-Ein-\/Zweikanal-Impulsgenerator ben\u00f6tigt einen oder zwei Ausgangskan\u00e4le des Typs Keysight 81131A (400 MHz, 3,8 V, 50 Ohm an 50 Ohm). Jeder Keysight 81130A 660 MHz Ein-\/Zweikanal-Impulsmustergenerator ben\u00f6tigt einen\/zwei der Ausgangskan\u00e4le Keysight 81112A (660 MHz, 2,5 V, 50 Ohm in 50 Ohm). Die Ausgangskan\u00e4le 81130, 81131A und 81132A k\u00f6nnen nicht in ein und demselben 81130A kombiniert werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Keysight 81130A ist mit einem oder zwei Keysight 81131A Ausgangsmodulen ein pr\u00e4ziser 400-MHz-Impulsdatengenerator f\u00fcr Ein- und Zweikanalbetrieb. Mit einem oder zwei Keysight 81132A Ausgangsmodulen wird der Keysight 81130A sogar zu einem pr\u00e4zisen 600-MHz-\/1,32-Gbit\/s-Impulsdatengenerator f\u00fcr Ein- und Zweikanalbetrieb. Dank seines PLL-Oszillators bietet der 81130A eine h\u00f6here Genauigkeit bei Verz\u00f6gerung und Impulsbreite als der 81110A. Dieser [&hellip;]<\/p>\n","protected":false},"featured_media":73427,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1614],"product_cat":[1740,1739,1753],"product_tag":[],"class_list":["post-47409","product","type-product","status-publish","has-post-thumbnail","manufacturer-keysight-de","product_cat-allgemeine-pruf-und-messtechnik","product_cat-pruf-und-messtechnik","product_cat-wellenform-und-funktionsgeneratoren","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product\/47409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media\/73427"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media?parent=47409"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/manufacturer?post=47409"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_cat?post=47409"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_tag?post=47409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}