{"id":55448,"date":"2025-10-01T02:00:58","date_gmt":"2025-10-01T00:00:58","guid":{"rendered":"https:\/\/rentaltec.com\/product\/fs-sns-smart-noise-source-from-10-mhz-up-to-110-ghz\/"},"modified":"2026-08-25T15:33:32","modified_gmt":"2026-08-25T13:33:32","slug":"fs-sns-smart-noise-source-from-10-mhz-up-to-110-ghz","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/de\/produkt\/fs-sns-smart-noise-source-from-10-mhz-up-to-110-ghz\/","title":{"rendered":"FS-SNS Smart noise source, from 10 MHz up to 110 GHz"},"content":{"rendered":"<p>R&amp;S <strong>FS-SNS<\/strong> Intelligente Rauschquelle, wichtige Fakten.<\/p>\n<ul>\n<li>Frequenzbereich: 18, 26, 40, 55, 67, 90 oder 110 GHz<\/li>\n<li>Unterst\u00fctzt von FSW, FSV3000, FSVA3000, FPS, FPL1000, FSWP, FSMR3000 und ZNL<\/li>\n<li>Automatisches Laden der ENR-Tabelle<\/li>\n<li>Tabelle mit ENR-Unsicherheit und Reflexionskoeffizienten zur automatischen Unsicherheitsberechnung<\/li>\n<li>Automatische Temperaturanzeige f\u00fcr verbesserte Genauigkeit<\/li>\n<\/ul>\n<p>Die intelligenten Rauschquellen der FS-SNS-Serie erm\u00f6glichen einfache und genaue Rauschzahl- und Verst\u00e4rkungsmessungen durch automatisches Laden aller notwendigen Parameter und Ber\u00fccksichtigung der Umgebungstemperatur. Die Messunsicherheit wird automatisch berechnet und kann sogar auf dem Ergebnisbildschirm angezeigt werden.<\/p>\n<p><strong>Verf\u00fcgbare Modelle<\/strong>:<\/p>\n<ul>\n<li>FS-SNS18: 10 MHz bis 18 GHz<\/li>\n<li>FS-SNS26: 10 MHz bis 26,5 GHz<\/li>\n<li>FS-SNS40: 100 MHz bis 40 GHz<\/li>\n<li>FS-SNS55: 100 MHz bis 55 GHz<\/li>\n<li>FS-SNS67: 100 MHz bis 67 GHz<\/li>\n<li>FS-SNS90: 60 GHz bis 90 GHz<\/li>\n<li>FS-SNS110: 75 GHz bis 110 GHz<\/li>\n<\/ul>\n<p>Um Rauschzahl- und Verst\u00e4rkungsmessungen mit einem Spektrumanalysator durchzuf\u00fchren, wird eine Rauschquelle (ENR-Quelle) ben\u00f6tigt, die dem Eingang des Pr\u00fcflings ein wohldefiniertes (und idealerweise \u201ewei\u00dfes\u201c) Rauschen hinzuf\u00fcgt. Die intelligenten Rauschquellen FS-SNS liefern die ENR-Tabellen und die Umgebungstemperatur in elektronischer Form an den Spektrumanalysator. Die Verbindung zum Analysator erfolgt \u00fcber ein 7-poliges Kabel zur Stromversorgung und Steuerung. F\u00fcr Ger\u00e4te ohne den erforderlichen Anschluss ist ein Adapterkabel optional erh\u00e4ltlich. Bei Anschluss an einen Spektrumanalysator mit der Anwendungs-Firmware FSx-K30 zur Rauschzahlmessung werden alle ben\u00f6tigten Parameter automatisch verarbeitet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R&amp;S FS-SNS Intelligente Rauschquelle, wichtige Fakten. Frequenzbereich: 18, 26, 40, 55, 67, 90 oder 110 GHz Unterst\u00fctzt von FSW, FSV3000, FSVA3000, FPS, FPL1000, FSWP, FSMR3000 und ZNL Automatisches Laden der ENR-Tabelle Tabelle mit ENR-Unsicherheit und Reflexionskoeffizienten zur automatischen Unsicherheitsberechnung Automatische Temperaturanzeige f\u00fcr verbesserte Genauigkeit Die intelligenten Rauschquellen der FS-SNS-Serie erm\u00f6glichen einfache und genaue Rauschzahl- und [&hellip;]<\/p>\n","protected":false},"featured_media":76173,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1631],"product_cat":[1755,1739,1759],"product_tag":[],"class_list":["post-55448","product","type-product","status-publish","has-post-thumbnail","manufacturer-rohde-schwarz-de","product_cat-funk-und-mikrowelle","product_cat-pruf-und-messtechnik","product_cat-rauschzahl-analysatoren-und-rauschgeneratoren","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product\/55448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media\/76173"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/media?parent=55448"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/manufacturer?post=55448"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_cat?post=55448"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/de\/wp-json\/wp\/v2\/product_tag?post=55448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}