{"id":43709,"date":"2025-05-13T11:31:16","date_gmt":"2025-05-13T09:31:16","guid":{"rendered":"https:\/\/rentaltec.com\/product\/n5245b-201-2-port-10-mhz-50-ghz-pna-x-network-analyzer-2-4-mm-m\/"},"modified":"2026-06-26T14:08:08","modified_gmt":"2026-06-26T12:08:08","slug":"n5245b-201-2-port-10-mhz-50-ghz-pna-x-network-analyzer-2-4-mm-m","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/n5245b-201-2-port-10-mhz-50-ghz-pna-x-network-analyzer-2-4-mm-m\/","title":{"rendered":"N5245B-201 2-Port, 10 MHz &#8211; 50 GHz PNA-X Network Analyzer, 2.4 mm (m)"},"content":{"rendered":"<p>Bien plus qu&#8217;un simple analyseur de r\u00e9seau vectoriel, le PNA-X est le banc de test micro-ondes le plus int\u00e9gr\u00e9 et flexible au monde pour la mesure de composants actifs tels que les amplificateurs, les m\u00e9langeurs et les convertisseurs de fr\u00e9quence. Il int\u00e8gre deux sources de signaux internes, un combinateur de signaux, des r\u00e9cepteurs de param\u00e8tres S et de bruit, des modulateurs et g\u00e9n\u00e9rateurs d&#8217;impulsions, ainsi qu&#8217;un ensemble de commutateurs et de points d&#8217;acc\u00e8s RF. Ces fonctionnalit\u00e9s mat\u00e9rielles constituent un noyau puissant pour une large gamme de mesures lin\u00e9aires et non lin\u00e9aires, le tout avec une seule connexion \u00e0 votre composant test\u00e9. \u2022 Simplifiez votre syst\u00e8me de test en rempla\u00e7ant un rack complet d&#8217;\u00e9quipements par un seul analyseur de r\u00e9seau PNA-X. \u2022 R\u00e9duisez le temps de test gr\u00e2ce \u00e0 la plus large gamme d&#8217;applications de mesure \u00e0 connexion unique. \u2022 Testez avec pr\u00e9cision la caract\u00e9risation lin\u00e9aire et non lin\u00e9aire des composants gr\u00e2ce \u00e0 une correction d&#8217;erreur avanc\u00e9e. \u2022 Choisissez parmi la plus large gamme d&#8217;applications de mesure du march\u00e9 pour une rapidit\u00e9, une pr\u00e9cision et une facilit\u00e9 d&#8217;utilisation optimales lors de tests RF avanc\u00e9s. \u2022 Acc\u00e9dez plus rapidement \u00e0 une analyse approfondie du comportement des composants gr\u00e2ce \u00e0 un \u00e9cran tactile multipoint et une interface utilisateur intuitive.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bien plus qu&#8217;un simple analyseur de r\u00e9seau vectoriel, le PNA-X est le banc de test micro-ondes le plus int\u00e9gr\u00e9 et flexible au monde pour la mesure de composants actifs tels que les amplificateurs, les m\u00e9langeurs et les convertisseurs de fr\u00e9quence. Il int\u00e8gre deux sources de signaux internes, un combinateur de signaux, des r\u00e9cepteurs de param\u00e8tres [&hellip;]<\/p>\n","protected":false},"featured_media":50587,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1537],"product_cat":[1701,1698,1682],"product_tag":[],"class_list":{"0":"post-43709","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-fr","7":"product_cat-analyseurs-de-reseau-et-kits-detalonnage--20ghz","8":"product_cat-rf-et-micro-ondes","9":"product_cat-test-et-mesure","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/43709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media\/50587"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=43709"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=43709"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=43709"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=43709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}