{"id":43883,"date":"2025-05-14T12:26:48","date_gmt":"2025-05-14T10:26:48","guid":{"rendered":"https:\/\/rentaltec.com\/product\/n5194a-520-50-mhz-20-ghz-uxg-agile-vector-adapter\/"},"modified":"2026-06-26T14:07:18","modified_gmt":"2026-06-26T12:07:18","slug":"n5194a-520-50-mhz-20-ghz-uxg-agile-vector-adapter","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/n5194a-520-50-mhz-20-ghz-uxg-agile-vector-adapter\/","title":{"rendered":"N5194A-520 50 MHz &#8211; 20 GHz UXG Agile Vector Adapter"},"content":{"rendered":"<p>Atteignez le plus haut niveau de fid\u00e9lit\u00e9 du secteur avec l&#8217;adaptateur vectoriel agile Keysight N5194A-520 20 GHz UXG. G\u00e9n\u00e9rez efficacement une modulation IQ complexe sur des signaux puls\u00e9s et simulez avec pr\u00e9cision des environnements de signaux complexes pour les radars et la guerre \u00e9lectronique, avec un r\u00e9alisme et une fiabilit\u00e9 accrus gr\u00e2ce au N5194A-520. Le N5194A-520 s&#8217;adapte rapidement \u00e0 de multiples configurations de canaux et de ports et assure une coh\u00e9rence entre diff\u00e9rentes sources, avec des configurations d&#8217;amplitude, de phase et de temps. Caract\u00e9ristiques et sp\u00e9cifications du Keysight N5194A-520\u00a0: Plage de fr\u00e9quences sp\u00e9cifi\u00e9e\u00a0: 50\u00a0MHz \u00e0 20\u00a0GHz\u00a0; Plage de fr\u00e9quences r\u00e9glables\u00a0: 10\u00a0MHz \u00e0 20\u00a0GHz\u00a0; R\u00e9solution de fr\u00e9quence CW\u00a0: 0,001\u00a0Hz\u00a0; Syst\u00e8me de g\u00e9n\u00e9ration de bande de base num\u00e9rique \u00e0 2\u00a0G\u00e9ch.\/s\u00a0; Production de signaux \u00e0 large bande (jusqu&#8217;\u00e0 1,6\u00a0GHz de bande passante)\u00a0; Vitesse de commutation de fr\u00e9quence, d&#8217;amplitude et de phase\u00a0: 170\u00a0ns. L&#8217;adaptateur vectoriel agile UXG Keysight N5194A-520 est disponible \u00e0 la location chez Rentaltec.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atteignez le plus haut niveau de fid\u00e9lit\u00e9 du secteur avec l&#8217;adaptateur vectoriel agile Keysight N5194A-520 20 GHz UXG. G\u00e9n\u00e9rez efficacement une modulation IQ complexe sur des signaux puls\u00e9s et simulez avec pr\u00e9cision des environnements de signaux complexes pour les radars et la guerre \u00e9lectronique, avec un r\u00e9alisme et une fiabilit\u00e9 accrus gr\u00e2ce au N5194A-520. Le [&hellip;]<\/p>\n","protected":false},"featured_media":50531,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1537],"product_cat":[1706,1698,1682],"product_tag":[],"class_list":{"0":"post-43883","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-fr","7":"product_cat-generateurs-de-signaux-8ghz","8":"product_cat-rf-et-micro-ondes","9":"product_cat-test-et-mesure","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/43883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media\/50531"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=43883"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=43883"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=43883"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=43883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}