{"id":44294,"date":"2025-05-14T12:10:59","date_gmt":"2025-05-14T10:10:59","guid":{"rendered":"https:\/\/rentaltec.com\/product\/dsox3054t-4-ch-500-mhz-oscilloscope\/"},"modified":"2026-06-26T14:02:26","modified_gmt":"2026-06-26T12:02:26","slug":"dsox3054t-4-ch-500-mhz-oscilloscope","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/dsox3054t-4-ch-500-mhz-oscilloscope\/","title":{"rendered":"DSOX3054T 4 Ch 500 MHz Oscilloscope"},"content":{"rendered":"<p>L&#8217;oscilloscope InfiniiVision s\u00e9rie 3000A a r\u00e9volutionn\u00e9 le march\u00e9. Offrant une r\u00e9solution de signal in\u00e9gal\u00e9e, une fonctionnalit\u00e9 sup\u00e9rieure \u00e0 celle de tout autre oscilloscope et une protection maximale de votre investissement, il a \u00e9galement \u00e9t\u00e9 l&#8217;oscilloscope le plus vendu de l&#8217;histoire de Hewlett Packard, Keysight et Keysight Technologies, Inc. La s\u00e9rie 3000T perp\u00e9tue cet h\u00e9ritage. Elle reprend tous les atouts r\u00e9volutionnaires du mod\u00e8le A et y ajoute un \u00e9cran tactile capacitif, une interface utilisateur tactile et le d\u00e9clencheur tactile de zone exclusif. Son taux de rafra\u00eechissement exceptionnel de 1 million d&#8217;images\/s vous assure une visualisation optimale de vos signaux et vous permet de d\u00e9tecter rapidement le moindre probl\u00e8me. De plus, ses nouvelles fonctionnalit\u00e9s d&#8217;analyse vous aident \u00e0 r\u00e9soudre rapidement les probl\u00e8mes les plus complexes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;oscilloscope InfiniiVision s\u00e9rie 3000A a r\u00e9volutionn\u00e9 le march\u00e9. Offrant une r\u00e9solution de signal in\u00e9gal\u00e9e, une fonctionnalit\u00e9 sup\u00e9rieure \u00e0 celle de tout autre oscilloscope et une protection maximale de votre investissement, il a \u00e9galement \u00e9t\u00e9 l&#8217;oscilloscope le plus vendu de l&#8217;histoire de Hewlett Packard, Keysight et Keysight Technologies, Inc. La s\u00e9rie 3000T perp\u00e9tue cet h\u00e9ritage. Elle [&hellip;]<\/p>\n","protected":false},"featured_media":50246,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1537],"product_cat":[1692,1682,1683],"product_tag":[],"class_list":{"0":"post-44294","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-fr","7":"product_cat-oscilloscopes-et-sondes--2ghz","8":"product_cat-test-et-mesure","9":"product_cat-usage-general","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/44294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media\/50246"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=44294"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=44294"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=44294"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=44294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}