{"id":44402,"date":"2025-05-14T12:09:05","date_gmt":"2025-05-14T10:09:05","guid":{"rendered":"https:\/\/rentaltec.com\/product\/89601b-bhf-custom-ofdm-modulation-analysis\/"},"modified":"2026-06-26T14:01:44","modified_gmt":"2026-06-26T12:01:44","slug":"89601b-bhf-custom-ofdm-modulation-analysis","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/89601b-bhf-custom-ofdm-modulation-analysis\/","title":{"rendered":"89601B-BHF Custom OFDM Modulation Analysis"},"content":{"rendered":"<p>Le logiciel d&#8217;analyse de signaux vectoriels 89600B vous offre une vision approfondie du fonctionnement interne des appareils sans fil complexes. L&#8217;option BHF permet aux ing\u00e9nieurs de configurer les outils de mesure OFDM fiables du 89600B pour tester leurs signaux OFDM personnalis\u00e9s. Ma\u00eetrisez la complexit\u00e9 des syst\u00e8mes OFDM multicanaux gr\u00e2ce \u00e0 une configuration de param\u00e8tres hautement personnalisable, capable de g\u00e9rer une large gamme de signaux. Profitez d&#8217;une s\u00e9lection compl\u00e8te de mesures pour les syst\u00e8mes SISO et MIMO, incluant des mesures de canal, de flux et intercanaux. Acc\u00e9dez aux mesures OFDM essentielles\u00a0: des mesures OFDM personnalis\u00e9es plus approfondies, telles que l&#8217;EVM, la diaphonie porteuse, l&#8217;adaptation I-Q et les param\u00e8tres de rafale. Des affichages de mesure flexibles permettent de caract\u00e9riser les signaux et de r\u00e9soudre les erreurs\u00a0; utilisez un affichage de constellation composite, une table de symboles avec les bits bruts d\u00e9modul\u00e9s, ainsi que la fr\u00e9quence du canal et les r\u00e9ponses impulsionnelles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le logiciel d&#8217;analyse de signaux vectoriels 89600B vous offre une vision approfondie du fonctionnement interne des appareils sans fil complexes. L&#8217;option BHF permet aux ing\u00e9nieurs de configurer les outils de mesure OFDM fiables du 89600B pour tester leurs signaux OFDM personnalis\u00e9s. Ma\u00eetrisez la complexit\u00e9 des syst\u00e8mes OFDM multicanaux gr\u00e2ce \u00e0 une configuration de param\u00e8tres hautement [&hellip;]<\/p>\n","protected":false},"featured_media":50208,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1537],"product_cat":[1708,1698,1682],"product_tag":[],"class_list":{"0":"post-44402","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-fr","7":"product_cat-analyseurs-de-spectre-et-de-signal-265-ghz","8":"product_cat-rf-et-micro-ondes","9":"product_cat-test-et-mesure","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/44402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media\/50208"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=44402"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=44402"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=44402"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=44402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}