{"id":44960,"date":"2025-05-13T11:55:07","date_gmt":"2025-05-13T09:55:07","guid":{"rendered":"https:\/\/rentaltec.com\/product\/smf100a-b122-22-ghz-analog-signal-generator-3-5-mmf\/"},"modified":"2026-06-26T14:15:02","modified_gmt":"2026-06-26T12:15:02","slug":"smf100a-b122-22-ghz-analog-signal-generator-3-5-mmf","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/smf100a-b122-22-ghz-analog-signal-generator-3-5-mmf\/","title":{"rendered":"SMF100A-B122 22 GHz Analog Signal Generator, 3.5 mm(f)"},"content":{"rendered":"<p>G\u00e9n\u00e9rateur de signaux 1 GHz-22 GHz. Le g\u00e9n\u00e9rateur de signaux micro-ondes SMF100A d\u00e9livre des signaux purs jusqu&#8217;\u00e0 43,5 GHz. De nouvelles options permettent d&#8217;\u00e9tendre sa plage de fr\u00e9quences jusqu&#8217;\u00e0 43,5 GHz et de la r\u00e9duire de 1 GHz \u00e0 100 kHz. Ces nouvelles fonctionnalit\u00e9s sont particuli\u00e8rement int\u00e9ressantes pour les secteurs de l&#8217;a\u00e9rospatiale et de la d\u00e9fense, ainsi que pour les fabricants de modules et de composants micro-ondes exigeant une source de signaux haute pr\u00e9cision et flexible couvrant une large bande de fr\u00e9quences. Le g\u00e9n\u00e9rateur de signaux micro-ondes SMF100A offre une puissance de sortie jusqu&#8217;\u00e0 26 dBm (\u00e0 20 GHz). Il constitue ainsi une source de signaux id\u00e9ale pour les mesures de m\u00e9langeurs. Cet appareil remplace m\u00eame les oscillateurs locaux des m\u00e9langeurs de haut niveau sans n\u00e9cessiter d&#8217;amplificateur suppl\u00e9mentaire, ce qui simplifie la configuration de test et r\u00e9duit les co\u00fbts. Le SMF100A pr\u00e9sente une valeur SSB exceptionnelle de -120 dBc typ. (\u00e0 un d\u00e9calage de 10 GHz\/10 kHz) et sa suppression des harmoniques \u00e9lev\u00e9es et des signaux parasites permet aux utilisateurs de piloter les dispositifs sous test (DUT) \u00e0 l&#8217;aide de signaux ultra-purs. Les utilisateurs b\u00e9n\u00e9ficient d&#8217;une source de signal flexible couvrant une large gamme de fr\u00e9quences et capable de r\u00e9pondre \u00e0 diverses exigences de mesure.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R&amp;S Signal Generator Base Unit SMF100A with Frequency range 1 GHz to 22 GHz SMF-B122 (1167.7004.03), AM\/FM\/PhiM\/Log AM Modulator SMF-B20 (1167.9594.02), Enhanced phase noise performance SMF-B22 (1415.2204.02), Step attenuatur 100 kHz &#8211; 22 GHz SMF-B26 (SMF-B26), High Output Power SMF-B32 (1415.2304.02), Low MW leakage SMF-B41 (1415.0901.02), Removable GPIB SMF-B83 (1167.6408.02)<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1554],"product_cat":[1706,1698,1682],"product_tag":[],"class_list":{"0":"post-44960","1":"product","2":"type-product","3":"status-publish","5":"manufacturer-rohde-schwarz-fr","6":"product_cat-generateurs-de-signaux-8ghz","7":"product_cat-rf-et-micro-ondes","8":"product_cat-test-et-mesure","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/44960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=44960"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=44960"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=44960"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=44960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}