{"id":45638,"date":"2025-05-14T12:23:04","date_gmt":"2025-05-14T10:23:04","guid":{"rendered":"https:\/\/rentaltec.com\/product\/n3301a-electronic-load-mainframe\/"},"modified":"2026-06-26T14:06:15","modified_gmt":"2026-06-26T12:06:15","slug":"n3301a-electronic-load-mainframe","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/n3301a-electronic-load-mainframe\/","title":{"rendered":"N3301A 600W DC electronic load mainframe, 2-slot"},"content":{"rendered":"<p>Le Keysight N3301A est un ch\u00e2ssis demi-rack \u00e0 2 emplacements qui accepte diff\u00e9rentes combinaisons de modules de charge N330x installables par l&#8217;utilisateur (150 W \u00e0 600 W) pour une configuration syst\u00e8me simplifi\u00e9e et une reconfiguration ult\u00e9rieure ais\u00e9e. Le N3301A peut accueillir jusqu&#8217;\u00e0 deux modules de charge N3302A, N3303A, N3304A et N3307A, ou un module de charge N3305A et un module de charge N3306A, permettant une puissance maximale totale de 600 watts.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Keysight N3301A est un ch\u00e2ssis demi-rack \u00e0 2 emplacements qui accepte diff\u00e9rentes combinaisons de modules de charge N330x installables par l&#8217;utilisateur (150 W \u00e0 600 W) pour une configuration syst\u00e8me simplifi\u00e9e et une reconfiguration ult\u00e9rieure ais\u00e9e. Le N3301A peut accueillir jusqu&#8217;\u00e0 deux modules de charge N3302A, N3303A, N3304A et N3307A, ou un module de [&hellip;]<\/p>\n","protected":false},"featured_media":52737,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1537],"product_cat":[1694,1682,1683],"product_tag":[],"class_list":{"0":"post-45638","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-fr","7":"product_cat-alimentations-de-laboratoire-charges-et-sourcemetres-smu","8":"product_cat-test-et-mesure","9":"product_cat-usage-general","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/45638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media\/52737"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=45638"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=45638"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=45638"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=45638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}