{"id":46982,"date":"2025-05-13T11:34:05","date_gmt":"2025-05-13T09:34:05","guid":{"rendered":"https:\/\/rentaltec.com\/product\/n8742a-3300w-600v-5-5a-dc-power-supply\/"},"modified":"2026-06-26T14:09:07","modified_gmt":"2026-06-26T12:09:07","slug":"n8742a-3300w-600v-5-5a-dc-power-supply","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/n8742a-3300w-600v-5-5a-dc-power-supply\/","title":{"rendered":"N8742A 3300W (600V\/5.5A) DC Power Supply"},"content":{"rendered":"<p>L&#8217;alimentation CC Keysight N8742A est une alimentation \u00e0 sortie unique de 600 V, 5,5 A et 3\u00a0300 W, au format compact 2U, offrant des performances optimales \u00e0 un prix avantageux. Les alimentations CC Keysight de base proposent les fonctionnalit\u00e9s essentielles pour un budget serr\u00e9. Elles offrent des options d&#8217;entr\u00e9e CA flexibles, un contr\u00f4le analogique\/r\u00e9sistant de la tension et du courant de sortie, ainsi que la possibilit\u00e9 de connecter plusieurs alimentations en parall\u00e8le ou en s\u00e9rie pour obtenir respectivement un courant ou une tension de sortie plus \u00e9lev\u00e9s. Caract\u00e9ristiques et sp\u00e9cifications principales\u00a0: &#8211; Sortie CC\u00a0: &#8211; Tension\u00a0: 600 V &#8211; Courant\u00a0: 5,5 A &#8211; Puissance\u00a0: 3\u00a0300 W &#8211; Pr\u00e9cision de programmation\u00a0: &#8211; Tension\u00a0: 0,05\u00a0% 300 mV &#8211; Courant\u00a0: 0,1\u00a0% 11 mA &#8211; Ondulation et bruit de sortie\u00a0: &#8211; CV cr\u00eate \u00e0 cr\u00eate\u00a0: 500 mV &#8211; CV efficace\u00a0: 120 Le Keysight N8742A est disponible \u00e0 la location ou en location-vente chez Rentaltec, avec un service client disponible 365 jours par an. \u00c9quipements de test de pointe\u00a0: nous investissons constamment dans de nouveaux \u00e9quipements pour accompagner les technologies \u00e9mergentes n\u00e9cessitant des appareils de test et de mesure \u00e9lectroniques. Nous sommes souvent parmi les premiers \u00e0 acqu\u00e9rir les nouveaux produits des plus grands fabricants d&#8217;\u00e9quipements de test et de mesure.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Keysight N8742A DC Power Supply, 600 V, 5.5 A, 3300 W.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1537],"product_cat":[1694,1682,1683],"product_tag":[],"class_list":{"0":"post-46982","1":"product","2":"type-product","3":"status-publish","5":"manufacturer-keysight-fr","6":"product_cat-alimentations-de-laboratoire-charges-et-sourcemetres-smu","7":"product_cat-test-et-mesure","8":"product_cat-usage-general","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/46982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=46982"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=46982"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=46982"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=46982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}