{"id":47222,"date":"2025-05-14T12:14:38","date_gmt":"2025-05-14T10:14:38","guid":{"rendered":"https:\/\/rentaltec.com\/product\/e5080b-4k2-4-port-9-khz-20-ghz-ena-network-analyzer-w-2nd-source\/"},"modified":"2026-06-26T14:03:45","modified_gmt":"2026-06-26T12:03:45","slug":"e5080b-4k2-4-port-9-khz-20-ghz-ena-network-analyzer-w-2nd-source","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/e5080b-4k2-4-port-9-khz-20-ghz-ena-network-analyzer-w-2nd-source\/","title":{"rendered":"E5080B-4K2 4-port, 9 kHz &#8211; 20 GHz ENA Network Analyzer (w 2nd Source)"},"content":{"rendered":"<p>Avec l&#8217;analyseur de r\u00e9seau Keysight E5080B-4K2, les techniciens peuvent choisir parmi une vaste gamme d&#8217;applications de mesure pour r\u00e9pondre aux exigences des tests RF et des mesures micro-ondes. L&#8217;E5080B-4K2 combine des g\u00e9n\u00e9rateurs d&#8217;impulsions et des modulateurs int\u00e9gr\u00e9s, l&#8217;analyse spectrale et l&#8217;analyse temporelle pour une caract\u00e9risation compl\u00e8te et rapide des dispositifs modernes, sans mat\u00e9riel de test suppl\u00e9mentaire. L&#8217;E5080B-4K2 est un analyseur de r\u00e9seau ENA flexible, adapt\u00e9 \u00e0 diverses applications en production, aux tests de composants et \u00e0 la v\u00e9rification de conception. Dot\u00e9 d&#8217;applications logicielles incluant des mesures de m\u00e9langeurs, de facteur de bruit et d&#8217;analyse spectrale, le Keysight E5080B-4K2 offre une analyse approfondie des exigences de test. Caract\u00e9ristiques et sp\u00e9cifications du Keysight E5080B-4K2\u00a0: Banc de test quatre ports avec seconde source\u00a0; Plage de fr\u00e9quences\u00a0: 9\u00a0kHz \u00e0 20\u00a0GHz\u00a0; Type de connecteur\u00a0: 3,5\u00a0mm (m)\u00a0; Stabilit\u00e9 en temp\u00e9rature\u00a0: 0,005\u00a0dB\/\u00b0C\u00a0; Puissance de sortie\u00a0: 10\u00a0dBm. L&#8217;analyseur de r\u00e9seau ENA quatre ports 20\u00a0GHz Keysight E5080B-4K2 (avec seconde source) est disponible \u00e0 la location.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec l&#8217;analyseur de r\u00e9seau Keysight E5080B-4K2, les techniciens peuvent choisir parmi une vaste gamme d&#8217;applications de mesure pour r\u00e9pondre aux exigences des tests RF et des mesures micro-ondes. L&#8217;E5080B-4K2 combine des g\u00e9n\u00e9rateurs d&#8217;impulsions et des modulateurs int\u00e9gr\u00e9s, l&#8217;analyse spectrale et l&#8217;analyse temporelle pour une caract\u00e9risation compl\u00e8te et rapide des dispositifs modernes, sans mat\u00e9riel de test [&hellip;]<\/p>\n","protected":false},"featured_media":50321,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1537],"product_cat":[1701,1698,1682],"product_tag":[],"class_list":{"0":"post-47222","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-fr","7":"product_cat-analyseurs-de-reseau-et-kits-detalonnage--20ghz","8":"product_cat-rf-et-micro-ondes","9":"product_cat-test-et-mesure","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/47222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media\/50321"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=47222"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=47222"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=47222"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=47222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}