{"id":47774,"date":"2025-05-14T11:41:59","date_gmt":"2025-05-14T09:41:59","guid":{"rendered":"https:\/\/rentaltec.com\/product\/6000ls-3-6000va-single-3-phase-ac-power-source\/"},"modified":"2026-06-26T13:54:27","modified_gmt":"2026-06-26T11:54:27","slug":"6000ls-3-6000va-single-3-phase-ac-power-source","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/6000ls-3-6000va-single-3-phase-ac-power-source\/","title":{"rendered":"6000LS-3 6000VA Single \/ 3-Phase AC Power Source"},"content":{"rendered":"<p>Le California Instruments 6000Ls-3 est une alimentation CA monophas\u00e9e\/triphas\u00e9e de 6\u00a0000 VA appartenant \u00e0 la s\u00e9rie Ls du fabricant. Version am\u00e9lior\u00e9e des alimentations CA classiques de la s\u00e9rie L de California Instruments, la s\u00e9rie Ls est id\u00e9ale pour les applications de d\u00e9fense et d&#8217;avionique. Elle offre de nombreuses fonctionnalit\u00e9s de base \u00e0 un prix avantageux. Des fonctionnalit\u00e9s suppl\u00e9mentaires, telles que la g\u00e9n\u00e9ration de formes d&#8217;onde arbitraires et les mesures harmoniques, peuvent \u00eatre ajout\u00e9es en option. Les principales caract\u00e9ristiques de l&#8217;alimentation CA 6000Ls-3 sont les suivantes\u00a0: configuration triphas\u00e9e, puissance de 6\u00a0kVA dans un seul ch\u00e2ssis, possibilit\u00e9 de combiner plusieurs ch\u00e2ssis pour des puissances allant jusqu&#8217;\u00e0 18\u00a0kVA. La s\u00e9rie Ls est enti\u00e8rement contr\u00f4l\u00e9e par microprocesseur et peut \u00eatre utilis\u00e9e \u00e0 l&#8217;aide d&#8217;un simple clavier en fa\u00e7ade. Deux commandes analogiques, situ\u00e9es \u00e0 c\u00f4t\u00e9 de l&#8217;\u00e9cran LCD alphanum\u00e9rique r\u00e9tro\u00e9clair\u00e9, permettent de faire varier dynamiquement la tension et la fr\u00e9quence de sortie. Pour les op\u00e9rations plus avanc\u00e9es, une s\u00e9rie de menus est disponible sur un \u00e9cran LCD \u00e0 double ligne \u00e0 contraste \u00e9lev\u00e9. Compatibilit\u00e9 ascendante avec la s\u00e9rie L\u00a0: la s\u00e9rie Ls offre une compatibilit\u00e9 fonctionnelle et de bus avec les alimentations CA de la s\u00e9rie L de CI. Gr\u00e2ce \u00e0 la syntaxe de commande APE (Abbreviated Plain English), la s\u00e9rie Ls peut \u00eatre utilis\u00e9e dans les syst\u00e8mes de test existants sans modification du code source. Le langage APE fait partie de l&#8217;option -GPIB, qui ajoute \u00e9galement l&#8217;interface GPIB\/IEEE-488. Programmation transitoire\u00a0: pour simuler les perturbations de ligne courantes, la s\u00e9rie LS propose une liste de transitoires. Ces transitoires peuvent \u00eatre programm\u00e9s depuis le panneau avant ou t\u00e9l\u00e9charg\u00e9s via l&#8217;interface \u00e0 l&#8217;aide du logiciel graphique fourni. Ce logiciel permet de cr\u00e9er sur disque des biblioth\u00e8ques de perturbations de ligne fr\u00e9quemment utilis\u00e9es pour un acc\u00e8s rapide. Une fois t\u00e9l\u00e9charg\u00e9, le programme de transitoires peut \u00eatre ex\u00e9cut\u00e9 depuis un PC ou depuis le panneau avant. La g\u00e9n\u00e9ration de transitoires CA permet de simuler les effets de variations rapides de tension, de fr\u00e9quence et de phase.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le California Instruments 6000Ls-3 est une alimentation CA monophas\u00e9e\/triphas\u00e9e de 6\u00a0000 VA appartenant \u00e0 la s\u00e9rie Ls du fabricant. Version am\u00e9lior\u00e9e des alimentations CA classiques de la s\u00e9rie L de California Instruments, la s\u00e9rie Ls est id\u00e9ale pour les applications de d\u00e9fense et d&#8217;avionique. Elle offre de nombreuses fonctionnalit\u00e9s de base \u00e0 un prix avantageux. [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1829],"product_cat":[1694,1682,1683],"product_tag":[],"class_list":{"0":"post-47774","1":"product","2":"type-product","3":"status-publish","5":"manufacturer-california-instruments-fr","6":"product_cat-alimentations-de-laboratoire-charges-et-sourcemetres-smu","7":"product_cat-test-et-mesure","8":"product_cat-usage-general","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/47774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=47774"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=47774"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=47774"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=47774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}