{"id":47984,"date":"2025-05-14T11:53:00","date_gmt":"2025-05-14T09:53:00","guid":{"rendered":"https:\/\/rentaltec.com\/product\/11945a-close-field-probe-set-9-khz-to-1-ghz\/"},"modified":"2026-06-26T13:57:02","modified_gmt":"2026-06-26T11:57:02","slug":"11945a-close-field-probe-set-9-khz-to-1-ghz","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/11945a-close-field-probe-set-9-khz-to-1-ghz\/","title":{"rendered":"11945A Close-Field Probe Set, 9 kHz to 1 GHz"},"content":{"rendered":"<p>Testez efficacement les composants de vos circuits gr\u00e2ce au kit de sondes de champ proche Keysight 11945A. Ces sondes utilisent des signaux impulsionnels pour des tests en circuit. Le Keysight 11945A est un outil de mesure performant pour les concepteurs \u00e9lectriques et m\u00e9caniques. Il d\u00e9tecte les sources d&#8217;interf\u00e9rences d\u00e8s les premi\u00e8res \u00e9tapes de la conception, facilitant ainsi leur \u00e9limination. Caract\u00e9ristiques et sp\u00e9cifications du Keysight 11945A\u00a0: Couverture compl\u00e8te de 9\u00a0kHz \u00e0 1\u00a0GHz. L&#8217;option E51 comprend le pr\u00e9amplificateur Keysight 11909A, un c\u00e2ble de type N de 914\u00a0mm (36\u00a0pouces) et une sacoche de transport.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Testez efficacement les composants de vos circuits gr\u00e2ce au kit de sondes de champ proche Keysight 11945A. Ces sondes utilisent des signaux impulsionnels pour des tests en circuit. Le Keysight 11945A est un outil de mesure performant pour les concepteurs \u00e9lectriques et m\u00e9caniques. Il d\u00e9tecte les sources d&#8217;interf\u00e9rences d\u00e8s les premi\u00e8res \u00e9tapes de la conception, [&hellip;]<\/p>\n","protected":false},"featured_media":49936,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1537],"product_cat":[1692,1682,1683],"product_tag":[],"class_list":{"0":"post-47984","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-fr","7":"product_cat-oscilloscopes-et-sondes--2ghz","8":"product_cat-test-et-mesure","9":"product_cat-usage-general","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/47984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media\/49936"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=47984"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=47984"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=47984"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=47984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}