{"id":59288,"date":"2025-11-11T03:05:31","date_gmt":"2025-11-11T02:05:31","guid":{"rendered":"https:\/\/rentaltec.com\/product\/zn-z5x-automatic-electronic-calibration-units-from-9-khz-up-to-50-ghz-2-or-4-ports\/"},"modified":"2026-06-26T14:15:45","modified_gmt":"2026-06-26T12:15:45","slug":"zn-z5x-automatic-electronic-calibration-units-from-9-khz-up-to-50-ghz-2-or-4-ports","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/fr\/produit\/zn-z5x-automatic-electronic-calibration-units-from-9-khz-up-to-50-ghz-2-or-4-ports\/","title":{"rendered":"ZN-Z5x automatic\/electronic calibration units, from 9 kHz up to 50 GHz, 2 or 4 ports"},"content":{"rendered":"<p>Unit\u00e9s d&#8217;\u00e9talonnage automatique R&#038;S ZN-Z5x\u00a0: points cl\u00e9s.<\/p>\n<ul>\n<li>Large plage de fr\u00e9quences\u00a0: 9\u00a0kHz \u00e0 50\u00a0GHz<\/li>\n<li>Temps de pr\u00e9chauffage quasi instantan\u00e9<\/li>\n<li>D\u00e9tection automatique et contr\u00f4le USB<\/li>\n<li>\u00c9talonnage multiport pris en charge<\/li>\n<\/ul>\n<p>Ces mod\u00e8les couvrent la plage de fr\u00e9quences de 9\u00a0kHz \u00e0 50\u00a0GHz et sont \u00e9quip\u00e9s de connecteurs de type N, 3,5\u00a0mm, 2,92\u00a0mm et 2,4\u00a0mm selon la plage de fr\u00e9quences. Ils sont disponibles en versions 2 ou 4\u00a0ports. La reconnexion permet \u00e9galement l&#8217;\u00e9talonnage multiport des syst\u00e8mes ZNBT, ZNB et des matrices de commutation. Les unit\u00e9s d&#8217;\u00e9talonnage ZN-Z5x prennent en charge les principales plages de fr\u00e9quences des analyseurs de r\u00e9seau R&#038;S et sont d\u00e9tect\u00e9es automatiquement via la connexion USB. Toutes les donn\u00e9es requises sont transf\u00e9r\u00e9es automatiquement vers le VNA.<br \/><strong>Mod\u00e8les disponibles<\/strong>:<\/p>\n<ul>\n<li>ZN-Z50, mod\u00e8le .30\u00a0: 9 kHz \u00e0 9 GHz, 2 ports<\/li>\n<li>ZN-Z50, mod\u00e8le .32\u00a0: 9 kHz \u00e0 26,5 GHz, 2 ports<\/li>\n<li>ZN-Z51, mod\u00e8les .32 et .72\u00a0: 100 kHz \u00e0 8,5 GHz, 2 ports<\/li>\n<li>ZN-Z51, mod\u00e8les .34 et .74\u00a0: 100 kHz \u00e0 8,5 GHz, 4 ports<\/li>\n<li>ZN-Z52, mod\u00e8le .30\u00a0: 100 kHz \u00e0 26,5 GHz, 4 ports<\/li>\n<li>ZN-Z53\u00a0; Mod\u00e8le .32\u00a0: et .72\u00a0: 100\u00a0kHz \u00e0 26,5\u00a0GHz, 2\u00a0ports<\/li>\n<li>ZN-Z54, mod\u00e8le .92\u00a0: 9\u00a0kHz \u00e0 40\u00a0GHz (caract\u00e9ris\u00e9 jusqu\u2019\u00e0 43,5\u00a0GHz), 2\u00a0ports<\/li>\n<li>ZN-Z55, mod\u00e8le .42\u00a0: 9\u00a0kHz \u00e0 50\u00a0GHz, 2\u00a0ports<\/li>\n<\/ul>\n<p>Pour le mod\u00e8le Z51, il est possible de configurer individuellement les ports. Chaque port peut \u00eatre adapt\u00e9 de fa\u00e7on permanente aux configurations suivantes\u00a0: N(m), 3,5\u00a0mm (m,f), 7\/16 (m,f) et 4,3-10 (f).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unit\u00e9s d&#8217;\u00e9talonnage automatique R&#038;S ZN-Z5x\u00a0: points cl\u00e9s. Large plage de fr\u00e9quences\u00a0: 9\u00a0kHz \u00e0 50\u00a0GHz Temps de pr\u00e9chauffage quasi instantan\u00e9 D\u00e9tection automatique et contr\u00f4le USB \u00c9talonnage multiport pris en charge Ces mod\u00e8les couvrent la plage de fr\u00e9quences de 9\u00a0kHz \u00e0 50\u00a0GHz et sont \u00e9quip\u00e9s de connecteurs de type N, 3,5\u00a0mm, 2,92\u00a0mm et 2,4\u00a0mm selon la plage [&hellip;]<\/p>\n","protected":false},"featured_media":59286,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1554],"product_cat":[1700,1701,1698,1682],"product_tag":[],"class_list":{"0":"post-59288","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-rohde-schwarz-fr","7":"product_cat-analyseurs-de-reseau-et-kits-detalonnage-20ghz","8":"product_cat-analyseurs-de-reseau-et-kits-detalonnage--20ghz","9":"product_cat-rf-et-micro-ondes","10":"product_cat-test-et-mesure","12":"first","13":"onbackorder","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product\/59288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media\/59286"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/media?parent=59288"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/manufacturer?post=59288"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_cat?post=59288"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/fr\/wp-json\/wp\/v2\/product_tag?post=59288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}