{"id":43873,"date":"2025-05-14T12:26:48","date_gmt":"2025-05-14T10:26:48","guid":{"rendered":"https:\/\/rentaltec.com\/product\/n5183b-540-9-khz-40-ghz-mxg-analog-signal-generator-2-4-mm-m\/"},"modified":"2026-08-25T15:07:05","modified_gmt":"2026-08-25T13:07:05","slug":"n5183b-540-9-khz-40-ghz-mxg-analog-signal-generator-2-4-mm-m","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/nl\/product\/n5183b-540-9-khz-40-ghz-mxg-analog-signal-generator-2-4-mm-m\/","title":{"rendered":"N5183B-540 9 kHz &#8211; 40 GHz MXG Analog Signal Generator, 2.4 mm (m)"},"content":{"rendered":"<p>De Keysight Technologies N5183B-540 is een MXG X-serie microgolf analoge signaalgenerator. Dankzij de voordelen op het gebied van formaat en snelheid is het een alternatief voor de analoge PSG. De Keysight Technologies N5183B-540 is ontworpen om de prestaties te leveren die u nodig hebt en biedt spectrale zuiverheid, uitgangsvermogen, schakelsnelheid en meer, voor het uitvoeren van module- en systeemtesten. De uitstekende hardwareprestaties van de Keysight Technologies N5183B-540 stellen u in staat de gewenste signalen te genereren, systeemverlies te compenseren, externe DUT&#8217;s te stimuleren en krachtige versterkers aan te sturen met behoud van signaalintegriteit. Met de Keysight Technologies N5183B-540<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Keysight N5183B MXG X-Series Microwave Analog Signal Generator with <span style=\"color:#262626\">N5183B-540 Frequency range, 9 kHz to 40 GHz<\/span><\/p>\n","protected":false},"featured_media":74918,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1460],"product_cat":[1410,1418,1394],"product_tag":[],"class_list":["post-43873","product","type-product","status-publish","has-post-thumbnail","manufacturer-keysight-nl","product_cat-rf-microgolf","product_cat-signaalgeneratoren-8ghz","product_cat-testen-meten","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/product\/43873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/media\/74918"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/media?parent=43873"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/manufacturer?post=43873"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/product_cat?post=43873"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/product_tag?post=43873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}