{"id":44266,"date":"2025-05-14T12:11:51","date_gmt":"2025-05-14T10:11:51","guid":{"rendered":"https:\/\/rentaltec.com\/product\/e4411b-1-5-ghz-portable-spectrum-analyzers-type-n-f\/"},"modified":"2026-06-26T12:50:41","modified_gmt":"2026-06-26T10:50:41","slug":"e4411b-1-5-ghz-portable-spectrum-analyzers-type-n-f","status":"publish","type":"product","link":"https:\/\/rentaltec.com\/nl\/product\/e4411b-1-5-ghz-portable-spectrum-analyzers-type-n-f\/","title":{"rendered":"E4411B 1.5 GHz Portable Spectrum analysers, Type N (f)"},"content":{"rendered":"<p>Als uw budget beperkt is, hoeft uw testapparatuur dat niet te zijn. De Keysight ESA-L-serie universele, draagbare spectrumanalysatoren biedt basisspectrumanalyse met de snelheid en nauwkeurigheid die u nodig hebt. Kenmerken: Compatibel met 8590-serie programmeercodes, multiformat RF-vermogensmeting, RF-sweep-tijd van vier milliseconden, algehele amplitude-nauwkeurigheid +\/- 1,1 dB, groot kleuren-VGA-scherm met hoge resolutie, robuuste, draagbare en weerbestendige behuizing, opwarmtijd van vijf minuten, ingebouwde helpknop.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als uw budget beperkt is, hoeft uw testapparatuur dat niet te zijn. De Keysight ESA-L-serie universele, draagbare spectrumanalysatoren biedt basisspectrumanalyse met de snelheid en nauwkeurigheid die u nodig hebt. Kenmerken: Compatibel met 8590-serie programmeercodes, multiformat RF-vermogensmeting, RF-sweep-tijd van vier milliseconden, algehele amplitude-nauwkeurigheid +\/- 1,1 dB, groot kleuren-VGA-scherm met hoge resolutie, robuuste, draagbare en weerbestendige behuizing, [&hellip;]<\/p>\n","protected":false},"featured_media":50264,"template":"","meta":{"_acf_changed":false,"content-type":""},"manufacturer":[1460],"product_cat":[1410,1421,1394],"product_tag":[],"class_list":{"0":"post-44266","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"manufacturer-keysight-nl","7":"product_cat-rf-microgolf","8":"product_cat-spectrum-en-signaalanalysatoren--265-ghz","9":"product_cat-testen-meten","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/product\/44266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/media\/50264"}],"wp:attachment":[{"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/media?parent=44266"}],"wp:term":[{"taxonomy":"manufacturer","embeddable":true,"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/manufacturer?post=44266"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/product_cat?post=44266"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rentaltec.com\/nl\/wp-json\/wp\/v2\/product_tag?post=44266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}